{"id":150,"count":4,"description":"","link":"https:\/\/fatordental.com.br\/index.php\/categoria-produto\/cirurgia-e-periodontia\/regeneracao-ossea\/","name":"Regenera\u00e7\u00e3o \u00d3ssea","slug":"regeneracao-ossea","taxonomy":"product_cat","parent":39,"meta":{"thumbnail_id":0},"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivos Regenera\u00e7\u00e3o \u00d3ssea - Fator Dental<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fatordental.com.br\/index.php\/categoria-produto\/cirurgia-e-periodontia\/regeneracao-ossea\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Regenera\u00e7\u00e3o \u00d3ssea - Fator Dental\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fatordental.com.br\/index.php\/categoria-produto\/cirurgia-e-periodontia\/regeneracao-ossea\/\" \/>\n<meta property=\"og:site_name\" content=\"Fator Dental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/fatordental.com.br\\\/index.php\\\/categoria-produto\\\/cirurgia-e-periodontia\\\/regeneracao-ossea\\\/\",\"url\":\"https:\\\/\\\/fatordental.com.br\\\/index.php\\\/categoria-produto\\\/cirurgia-e-periodontia\\\/regeneracao-ossea\\\/\",\"name\":\"Arquivos Regenera\u00e7\u00e3o \u00d3ssea - Fator Dental\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fatordental.com.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fatordental.com.br\\\/index.php\\\/categoria-produto\\\/cirurgia-e-periodontia\\\/regeneracao-ossea\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fatordental.com.br\\\/index.php\\\/categoria-produto\\\/cirurgia-e-periodontia\\\/regeneracao-ossea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/fatordental.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cirurgia e Periodontia\",\"item\":\"https:\\\/\\\/fatordental.com.br\\\/index.php\\\/categoria-produto\\\/cirurgia-e-periodontia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Regenera\u00e7\u00e3o \u00d3ssea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fatordental.com.br\\\/#website\",\"url\":\"https:\\\/\\\/fatordental.com.br\\\/\",\"name\":\"Fator Dental\",\"description\":\"Produtos Ondontol\u00f3gicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/fatordental.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fatordental.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fatordental.com.br\\\/#organization\",\"name\":\"Fator Dental\",\"url\":\"https:\\\/\\\/fatordental.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fatordental.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fatordental.com.br\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_fator.png\",\"contentUrl\":\"https:\\\/\\\/fatordental.com.br\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_fator.png\",\"width\":400,\"height\":256,\"caption\":\"Fator Dental\"},\"image\":{\"@id\":\"https:\\\/\\\/fatordental.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/fatordental\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Regenera\u00e7\u00e3o \u00d3ssea - Fator Dental","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fatordental.com.br\/index.php\/categoria-produto\/cirurgia-e-periodontia\/regeneracao-ossea\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos Regenera\u00e7\u00e3o \u00d3ssea - Fator Dental","og_url":"https:\/\/fatordental.com.br\/index.php\/categoria-produto\/cirurgia-e-periodontia\/regeneracao-ossea\/","og_site_name":"Fator Dental","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fatordental.com.br\/index.php\/categoria-produto\/cirurgia-e-periodontia\/regeneracao-ossea\/","url":"https:\/\/fatordental.com.br\/index.php\/categoria-produto\/cirurgia-e-periodontia\/regeneracao-ossea\/","name":"Arquivos Regenera\u00e7\u00e3o \u00d3ssea - Fator Dental","isPartOf":{"@id":"https:\/\/fatordental.com.br\/#website"},"breadcrumb":{"@id":"https:\/\/fatordental.com.br\/index.php\/categoria-produto\/cirurgia-e-periodontia\/regeneracao-ossea\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/fatordental.com.br\/index.php\/categoria-produto\/cirurgia-e-periodontia\/regeneracao-ossea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/fatordental.com.br\/"},{"@type":"ListItem","position":2,"name":"Cirurgia e Periodontia","item":"https:\/\/fatordental.com.br\/index.php\/categoria-produto\/cirurgia-e-periodontia\/"},{"@type":"ListItem","position":3,"name":"Regenera\u00e7\u00e3o \u00d3ssea"}]},{"@type":"WebSite","@id":"https:\/\/fatordental.com.br\/#website","url":"https:\/\/fatordental.com.br\/","name":"Fator Dental","description":"Produtos Ondontol\u00f3gicos","publisher":{"@id":"https:\/\/fatordental.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fatordental.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/fatordental.com.br\/#organization","name":"Fator Dental","url":"https:\/\/fatordental.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fatordental.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/fatordental.com.br\/wp-content\/uploads\/2023\/02\/logo_fator.png","contentUrl":"https:\/\/fatordental.com.br\/wp-content\/uploads\/2023\/02\/logo_fator.png","width":400,"height":256,"caption":"Fator Dental"},"image":{"@id":"https:\/\/fatordental.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/fatordental\/"]}]}},"_links":{"self":[{"href":"https:\/\/fatordental.com.br\/index.php\/wp-json\/wp\/v2\/product_cat\/150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fatordental.com.br\/index.php\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/fatordental.com.br\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/fatordental.com.br\/index.php\/wp-json\/wp\/v2\/product_cat\/39"}],"wp:post_type":[{"href":"https:\/\/fatordental.com.br\/index.php\/wp-json\/wp\/v2\/product?product_cat=150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}